{"id":2057,"date":"2017-03-14T12:42:57","date_gmt":"2017-03-14T16:42:57","guid":{"rendered":"http:\/\/www.modestmillionaires.com\/?p=63"},"modified":"2025-10-13T04:32:33","modified_gmt":"2025-10-13T04:32:33","slug":"a-propos-de-moi","status":"publish","type":"post","link":"https:\/\/modestmillionaires.com\/fr\/a-propos-de-moi\/","title":{"rendered":"\u00c0 propos de moi"},"content":{"rendered":"\n<p>Salut! Je m\u2019appelle Mel et je suis la blogueuse derri\u00e8re <em>Modest Millionaires<\/em>. J\u2019habite au Qu\u00e9bec et mon contenu est disponible en fran\u00e7ais et en anglais.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-medium\"><img decoding=\"async\" src=\"http:\/\/www.modestmillionaires.com\/wp-content\/uploads\/2021\/04\/PXL_20210203_201749343.PORTRAIT_2-1-225x300.jpg\" alt=\"\" class=\"wp-image-2254\"\/><\/figure>\n\n\n\n<p>J\u2019ai toujours \u00e9t\u00e9 attir\u00e9e par les finances. En fait, lors de mon choix de programme d\u2019\u00e9tude universitaire, j\u2019h\u00e9sitais entre \u00e9tudier en d\u00e9veloppement international ou en administration des affaires. Ces deux passions se sont en quelque sorte rencontr\u00e9es gr\u00e2ce \u00e0 un programme \u00e0 HEC Montr\u00e9al o\u00f9 j\u2019ai pu suivre \u2153 de mes cours en administration des affaires en fran\u00e7ais, un autre tiers en anglais et le reste en espagnol tout en passant un semestre \u00e0 l\u2019\u00e9tranger.<\/p>\n\n\n\n<p>Cela m\u2019a ensuite men\u00e9e \u00e0 ma carri\u00e8re en tant qu\u2019analyste d\u2019affaires principale pour le gouvernement f\u00e9d\u00e9ral dans des r\u00f4les en liens avec l\u2019industrie de la radio et des t\u00e9l\u00e9communications &#8211; interagissant avec des petites et grandes organisations dans le domaine tel que Bell, Telus, Rogers et Vid\u00e9otron<\/p>\n\n\n\n<p>Pendant ce temps, j\u2019ai utilis\u00e9 ce que j\u2019ai appris au cours de mes \u00e9tudes et de ma carri\u00e8re, comme la mani\u00e8re dont les entreprises ou les organisations remplissent leur mission de mani\u00e8re profitable ou durable, et je me suis mise \u00e0 l\u2019appliquer aux finances de ma propre famille. C\u2019est ainsi que nous avons cr\u00e9\u00e9 notre <a href=\"http:\/\/www.modestmillionaires.com\/fr\/2017\/03\/17\/le-plan-2025-des-modest-millionaires\/\"><strong>plan de 10 ans pour atteindre l\u2019ind\u00e9pendance financi\u00e8re<\/strong><\/a> tout en l\u2019ajustant \u00e0 nos besoins lorsque notre famille s&rsquo;est agrandie avec l&rsquo;arriv\u00e9e d\u2019un puis d\u2019un deuxi\u00e8me enfant.<\/p>\n\n\n\n<p>Au cours des 5 derni\u00e8res ann\u00e9es, j\u2019ai commenc\u00e9 \u00e0 accompagner des individus pour surmonter leurs d\u00e9fis et prendre le contr\u00f4le de leurs finances. C\u2019est devenu ma petite entreprise \u00e0 temps perdu les soirs et fin de semaines. J\u2019ai d\u00e9velopp\u00e9 une grande passion \u00e0 guider les autres vers leur ind\u00e9pendance financi\u00e8re.&nbsp;<\/p>\n\n\n\n<p>Ceci, combin\u00e9 \u00e0 <a href=\"http:\/\/www.modestmillionaires.com\/fr\/progres-des-modest-millionaires\/\">la progression vers notre objectif d\u2019ind\u00e9pendance financi\u00e8re<\/a> m\u2019a amen\u00e9 \u00e0 d\u00e9cider de <a href=\"http:\/\/www.modestmillionaires.com\/fr\/2020\/10\/23\/prendre-une-annee-sabbatique-afin-de-tester-coast-fi\/\"><strong>prendre une ann\u00e9e sabbatique<\/strong><\/a> de ma carri\u00e8re de fonctionnaire pour, tout d\u2019abord, avoir la flexibilit\u00e9 en tant que parent dans un temps de pand\u00e9mie et d\u00e9dier 10 \u00e0 20h par semaine \u00e0 mon entreprise d\u2019\u00e9ducation et <a href=\"http:\/\/www.modestmillionaires.com\/fr\/coaching-2\/\">d\u2019accompagnement financier.<\/a>&nbsp;<\/p>\n\n\n\n<p><strong>Je teste donc un mode de vie Coast FI et je suis ravie de partager mon exp\u00e9rience avec vous!<\/strong><\/p>\n\n\n\n<p><strong><em>Psst, si vous souhaitez \u00eatre les premiers \u00e0 en savoir plus sur mes projets \u00e0 venir et mon coaching en g\u00e9n\u00e9ral, assurez-vous de vous abonner \u00e0 <a href=\"http:\/\/email.modestmillionaires.com\/infolettre\">mon infolettre<\/a>! <\/em><\/strong> <\/p>\n\n\n<div class=\"\"><div class='_form_2'><\/div><script type='text\/javascript' src='https:\/\/mdorionservices.activehosted.com\/f\/embed.php?static=0&id=2&6A049F6FDCBA7&nostyles=0&preview=0'><\/script><\/div>\n\n\n<h6 class=\"wp-block-heading\"><a href=\"http:\/\/www.modestmillionaires.com\/fr\/avertissement\/\">Avertissement:<\/a><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\">Les articles publi\u00e9s sur ce site sont uniquement \u00e0 titre d\u2019information et de divertissement. L\u2019information partag\u00e9e sur Modest Millionaires repr\u00e9sente l\u2019opinion de l\u2019auteur et ne peut \u00eatre consid\u00e9r\u00e9e comme des recommandations financi\u00e8res professionnelles. Le but de ce blogue est d\u2019effectuer le suivi de notre parcours personnel vers l\u2019ind\u00e9pendance financi\u00e8re.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Salut! Je m\u2019appelle Mel et je suis la blogueuse derri\u00e8re Modest Millionaires. J\u2019habite au Qu\u00e9bec et mon contenu est disponible en fran\u00e7ais et en anglais. J\u2019ai toujours \u00e9t\u00e9 attir\u00e9e par les finances. En fait, lors de mon choix de programme d\u2019\u00e9tude universitaire, j\u2019h\u00e9sitais entre \u00e9tudier en d\u00e9veloppement international ou en administration des affaires. Ces deux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[182,1],"tags":[],"class_list":["post-2057","post","type-post","status-publish","format-standard","hentry","category-non-categorise","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts\/2057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/comments?post=2057"}],"version-history":[{"count":1,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts\/2057\/revisions"}],"predecessor-version":[{"id":6082,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts\/2057\/revisions\/6082"}],"wp:attachment":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/media?parent=2057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/categories?post=2057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/tags?post=2057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}