{"id":2134,"date":"2020-08-12T07:00:00","date_gmt":"2020-08-12T11:00:00","guid":{"rendered":"http:\/\/www.modestmillionaires.com\/?p=2036"},"modified":"2025-10-13T16:06:28","modified_gmt":"2025-10-13T16:06:28","slug":"sentourer-de-sources-dinspiration","status":"publish","type":"post","link":"https:\/\/modestmillionaires.com\/fr\/sentourer-de-sources-dinspiration\/","title":{"rendered":"S\u2019entourer de sources d\u2019inspiration"},"content":{"rendered":"\n<p>Plus vous vous entourez de sources d\u2019inspiration, plus vous avez l\u2019occasion de progresser vers vos objectifs avec assiduit\u00e9. L\u2019inspiration peut prendre plusieurs formes. Il s\u2019agit essentiellement d\u2019exemples illustrant l&rsquo;accomplissement d\u2019objectifs que vous d\u00e9sirez r\u00e9aliser ou encore de personnes qui, pour vous, ont des comportements mod\u00e8les.&nbsp;<\/p>\n\n\n\n<p>Les sources d\u2019inspiration peuvent \u00eatre non-interactives, tels que lire des blogs ou livres ou \u00e9couter des podcasts de gens ayant accompli des choses que vous aimeriez accomplir. Elles peuvent \u00e9galement prendre une forme plus interactive tel que la participation \u00e0 un cours ou webinar, partager au sein d\u2019un groupe Facebook et se r\u00e9unir avec des gens passionn\u00e9s par les m\u00eames sujets que nous.&nbsp;<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-pale-cyan-blue-background-color has-text-color has-background\"><strong>\u00c0 ce sujet, j&rsquo;organise une rencontre virtuelle FI Qu\u00e9bec (en fran\u00e7ais seulement pour cette fois-ci). Tout au bas de cet article vous trouverez l\u2019information pour vous y inscrire.&nbsp;<\/strong><\/p>\n\n\n\n<a href=\"https:\/\/www.pinterest.ca\/pin\/731483164470339720\" target=\"_blank\" rel=\"noopener noreferrer\"><figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/www.modestmillionaires.com\/wp-content\/uploads\/2020\/08\/sources-inspiration-683x1024.png\" alt=\"\" class=\"wp-image-2037\" data-pin-description=\"Entourez-vous de sources d'inspiration pour accomplir vos objectifs, programmer votre cerveau \u00e0 voir des opportunit\u00e9 et renforcez votre confiance | Outils et conseil pour \u00e9tablie et atteindre vos objectifs | D\u00e9veloppement personel | Objectifs | Libert\u00e9 financi\u00e8re | Communaut\u00e9 | Inspiration\"><\/figure><\/a>\n\n\n\n<h4 class=\"wp-block-heading\">L\u2019inspiration peut mener vers un chemin plus agr\u00e9able.<\/h4>\n\n\n\n<p>Une des raisons pour lesquelles j\u2019ai d\u00e9cid\u00e9 de cr\u00e9er ce blog \u00e9tait que je pensais que l\u2019\u00e9criture au sujet de l\u2019ind\u00e9pendance financi\u00e8re m&rsquo;am\u00e8nerait \u00e0 explorer et trouver des moyens d\u2019acc\u00e9l\u00e9rer nos \u00e9conomies. Je croyais que d\u00e9tailler les diff\u00e9rents d\u00e9fis au cours de notre cheminement pourrait m\u2019aider \u00e0 faire preuve d&rsquo;assiduit\u00e9 et \u00e0 continuer \u00e0 m\u2019entourer de sources d\u2019inspiration pour nous aider sur notre propre chemin.&nbsp;<\/p>\n\n\n\n<p>Plus de 3 ans plus tard, je me rends compte que ce qui \u00e9tait au d\u00e9part un simple passe-temps m\u2019a en fait permis de trouver des moyens d\u2019augmenter mon bonheur et de concevoir une vie que je pr\u00e9f\u00e8re en chemin vers notre objectif FI, am\u00e9liorant ainsi notre trajectoire. L\u2019inspiration a eu une port\u00e9e bien au-del\u00e0 de cette id\u00e9e de trouver d\u2019autres moyens d\u2019\u00e9conomiser de l\u2019argent.&nbsp;<\/p>\n\n\n\n<p>Par exemple, mon amie Jessica du blog The Fioneers, que j\u2019ai rencontr\u00e9e gr\u00e2ce \u00e0 l\u2019\u00e9criture de ce blog, a demand\u00e9 si je voulais rejoindre un groupe ax\u00e9 sur <a href=\"https:\/\/thefioneers.com\/accountability-lifestyle-design\/\">le design de son mode de vie id\u00e9al<\/a>. \u00c0 travers cette exp\u00e9rience, notre petit groupe de blogueurs ayant tous lu le livre <a href=\"https:\/\/www.amazon.ca\/gp\/product\/0451494083\/ref=as_li_tl?ie=UTF8&amp;camp=15121&amp;creative=330641&amp;creativeASIN=0451494083&amp;linkCode=as2&amp;tag=modestmill0ad-20&amp;linkId=df041bb8b7e7c436065cfa3716217ef4\">Designing your Life<\/a> se rencontrait r\u00e9guli\u00e8rement pour se soutenir \u00e0 travers les exercices recommand\u00e9s par le livre. J\u2019ai tranquillement mis en oeuvre certains changements avec le soutien de ce groupe pour m\u2019aider \u00e0 relever les d\u00e9fis puis tester et perfectionner ma vision de mon mode de vie id\u00e9al.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Il n\u2019est pas rare que les amis extraordinaires que je me suis fait gr\u00e2ce au blog se soutiennent mutuellement dans des objectifs allant bien au-del\u00e0 du sujet des finances. Un parfait exemple de ceci est mon amie Purple de <a href=\"https:\/\/apurplelife.com\/\">A Purple Life<\/a> qui tient sur Twitter une cha\u00eene de responsabilisation \u00e0 toutes les semaines pour nous aider \u00e0 nous rappeler ce sur quoi nous d\u00e9cidons de nous concentrer.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">It&#39;s August&#8230;How did that happen\ud83e\udd37\ud83c\udffe\u200d\u2640\ufe0f? Anyway, this is your Breaking Purple Bulletin\ud83d\udcf0. Let&#39;s get shit done\ud83d\ude4c\ud83c\udffe!<a href=\"https:\/\/twitter.com\/ModMillionaires?ref_src=twsrc%5Etfw\">@ModMillionaires<\/a>: How&#39;s your task list going? How&#39;s logging on MFP? You got this! <a href=\"https:\/\/twitter.com\/iliketodabble?ref_src=twsrc%5Etfw\">@iliketodabble<\/a>: How are you lady? How&#39;s <a href=\"https:\/\/twitter.com\/hikingandroadtr?ref_src=twsrc%5Etfw\">@hikingandroadtr<\/a>?<br><br>1\/7<\/p>&mdash; A Purple Life (@APurpleLifeBlog) <a href=\"https:\/\/twitter.com\/APurpleLifeBlog\/status\/1291018919059181575?ref_src=twsrc%5Etfw\">August 5, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Sur le blog, j\u2019ai \u00e9galement \u00e9crit davantage sur la<a href=\"http:\/\/www.modestmillionaires.com\/fr\/2018\/09\/24\/augmenter-notre-niveau-de-bonheur-au-travail\/\"> recherche du bonheur au travail<\/a>. J\u2019ai explor\u00e9 plus en d\u00e9tail des ressources telles que le <a href=\"https:\/\/www.madfientist.com\/podcast\/\">podcast de Mad Fientist<\/a> puis les <a href=\"https:\/\/www.madfientist.com\/first-year-of-freedom\/\">le\u00e7ons apprises au cours de ses premi\u00e8res ann\u00e9es de FI <\/a>&nbsp;et de ce qu\u2019il aurait fait diff\u00e9remment en cours de route. Ses le\u00e7ons et sa trajectoire ont jou\u00e9 un r\u00f4le dans l\u2019inspiration qui m\u2019a amen\u00e9e \u00e0 <a href=\"http:\/\/www.modestmillionaires.com\/fr\/2019\/06\/06\/negocier-une-entente-pour-faire-du-teletravail\/\">n\u00e9gocier une entente de t\u00e9l\u00e9travail<\/a>.&nbsp;<\/p>\n\n\n\n<p>Les sources d\u2019inspiration qui m\u2019ont entour\u00e9e dans mon \u00e9criture sur mon propre parcours m\u2019ont men\u00e9es vers un chemin plus agr\u00e9able en route vers l\u2019ind\u00e9pendance financi\u00e8re. Un exemple frappant de ce principe est cette r\u00e9cente <a href=\"https:\/\/thefioneers.com\/active-income-retirement\/\">entrevue sur le blog The Fioneers blog <\/a>o\u00f9 un couple partage leur histoire d\u2019avoir fait le saut vers une semi-retraite 3 ans plus t\u00f4t gr\u00e2ce \u00e0 la d\u00e9couverte de Slow FI et du concept de revenu actif suite \u00e0 leur participation \u00e0 des rencontres Choose FI locales.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Programm\u00e9 vos cerveaux \u00e0 identifier des opportunit\u00e9s<\/h4>\n\n\n\n<p>Pour explorer davantage ce d\u00e9sir <a href=\"http:\/\/www.modestmillionaires.com\/fr\/2018\/09\/24\/augmenter-notre-niveau-de-bonheur-au-travail\/\">d\u2019augmenter notre bonheur pendant mes ann\u00e9es au travail<\/a>, j\u2019ai commenc\u00e9 \u00e0 lire sur la psychologie positive dans le monde du travail avec des livres comme <a href=\"https:\/\/www.amazon.ca\/gp\/product\/0307591549\/ref=as_li_tl?ie=UTF8&amp;camp=15121&amp;creative=330641&amp;creativeASIN=0307591549&amp;linkCode=as2&amp;tag=modestmill0e7-20&amp;linkId=d1b62ac395d8880194e83f276fc87ea2\">Happiness Advantage<\/a>.<\/p>\n\n\n\n<p>Un principe int\u00e9ressant dans ce livre qui s\u2019appelle l\u2019effet Tetris montre que nos cerveaux peuvent \u00eatre programm\u00e9s de fa\u00e7on \u00e0 identifier les bonnes choses dans la vie- pour nous aider \u00e0 percevoir plus de possibilit\u00e9s, pour ressentir plus d\u2019\u00e9nergie et pour r\u00e9ussir \u00e0 des niveaux plus \u00e9lev\u00e9s.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Plus j\u2019explore le concept du bonheur, plus je me trouve attir\u00e9 vers des opportunit\u00e9s d\u2019auto-exploration et vers des r\u00e9flexions quant au sens de mon ind\u00e9pendance financi\u00e8re.&nbsp; Possiblement qu\u2019\u00e9crire sur notre cheminement tout en m\u2019entourant de sources d\u2019inspiration d\u2019autres personnes qui poursuivent le m\u00eame objectif a aid\u00e9 mon cerveau \u00e0 se programmer pour voir et saisir ces opportunit\u00e9s.&nbsp;<\/p>\n\n\n\n<p>Une de ces actions simples a \u00e9t\u00e9 de lire le livre <a href=\"https:\/\/www.amazon.ca\/gp\/product\/0316450898\/ref=as_li_tl?ie=UTF8&amp;camp=15121&amp;creative=330641&amp;creativeASIN=0316450898&amp;linkCode=as2&amp;tag=modestmill0ad-20&amp;linkId=3fce37b14d74add9d065e6fce7e955a8\">Work Optional<\/a> qui m\u2019a guid\u00e9e \u00e0 d\u00e9finir ma vie de travail optionnel avec plus de clart\u00e9. \u00c0 travers des exercices qui m\u2019ont aid\u00e9e \u00e0 renouer avec ce qui est le plus important pour m\u2019\u00e9panouir dans ma vie, j\u2019ai pu observer l\u2019importance de la valeur de la communaut\u00e9 pour moi.<\/p>\n\n\n\n<p>M\u2019appuyant sur les exercices du livre et me recentrer sur l&rsquo;importance de la communaut\u00e9 pour moi, a contribu\u00e9 \u00e0 diminuer mon syndrome d\u2019imposteur et \u00e0 me sentir plus confiante quant \u00e0 ma d\u00e9cision en 2019 d\u2019assister \u00e0 Fincon, une conf\u00e9rence pour les cr\u00e9ateurs de contenu financier.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Renforcer la confiance&nbsp;<\/h4>\n\n\n\n<p>En participant \u00e0 cette conf\u00e9rence et \u00e0 d\u2019autres rencontres li\u00e9es au sujet de l\u2019ind\u00e9pendance financi\u00e8re, j\u2019ai pu rencontrer des gens qui ont r\u00e9alis\u00e9 certains de mes r\u00eaves et qui vient pr\u00e9sentement cette vie de FI \u00e0 laquelle je travaille depuis plus de 6 ans. Voir d\u2019autres personnes qui ont d\u00e9j\u00e0 atteint FIRE et avoir des conversations sur leurs progr\u00e8s, leur \u00e9tat d\u2019esprit et leur vie actuelle est source \u00e0 renforcer la confiance pour mon propre projet: cela le rend plus concret et r\u00e9aliste.<\/p>\n\n\n\n<p>R\u00eaver de ce grand plan est une chose, mais rencontrer des gens qui l\u2019ont ex\u00e9cut\u00e9 en est une autre. Ce sont de vraies personnes qui ont saisi certaines opportunit\u00e9s et surmont\u00e9 certaines peurs qui ont surgi au cours du cheminement pour enfin atteindre cet objectif.&nbsp;<\/p>\n\n\n\n<p>J\u2019ai \u00e9galement pu explorer plus en profondeur l\u2019id\u00e9e du <a href=\"http:\/\/www.modestmillionaires.com\/fr\/coaching-2\/\">coaching financier<\/a> en assistant \u00e0 FinCon. J\u2019ai eu l\u2019occasion de discuter avec des personnes qui dirigent des entreprises vou\u00e9es \u00e0 aider les gens \u00e0 prendre contr\u00f4le de leurs finances. J\u2019ai pu poser des questions par rapport \u00e0 leurs d\u00e9buts, les inconv\u00e9nients et d\u00e9fis qu\u2019ils ont rencontr\u00e9 puis demand\u00e9 des conseils pour quiconque souhaite s\u2019y lancer soi-m\u00eame.<\/p>\n\n\n\n<p>Je fais m\u00eame parti aujourd\u2019hui d\u2019un petit groupe form\u00e9 de coach dans diff\u00e9rents domaines qui se rencontre r\u00e9guli\u00e8rement pour discuter de notre progr\u00e8s et de nos d\u00e9fis. Une sorte de \u201c<em>mastermind<\/em>\u201d ou de mentorat entre pairs qui est si enrichissant et sert \u00e0 continuellement m\u2019entourer de sources d\u2019inspiration.<\/p>\n\n\n\n<p>Voir une autre personne surmonter ses propres peurs et obstacles est v\u00e9ritablement inspirant. Curieusement, il est souvent plus facile de croire aux objectifs de nos amis et de les soutenir que de croire en nous-m\u00eames. D\u00e9couvrir les processus que d\u2019autres ont mis en place en cours de route vers leurs objectifs puis nous rendre compte que nous avons tous des peurs \u00e0 surmonter peut en fait nous aider \u00e0 devenir plus courageux avec nos propres objectifs.&nbsp;<\/p>\n\n\n\n<p>Le podcast <a href=\"https:\/\/www.jillianjohnsrud.com\/everyday-courage\/\">Everyday Courage<\/a> de Jillian Johnsruf entoure cette id\u00e9e selon laquelle vous n\u2019avez pas besoin d\u2019\u00eatre parfait pour progresser, il vous suffit d\u2019\u00eatre un peu plus courageux. \u00c9couter un podcast inspirant comme celui-ci est une autre fa\u00e7on de continuer \u00e0 vous entourer de sources d\u2019inspiration et de renforcer votre confiance pour passer \u00e0 l\u2019action et r\u00e9aliser vos objectifs.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conclusion<\/h4>\n\n\n\n<p>Vous pouvez trouver de nombreuses fa\u00e7ons de continuer \u00e0 vous entourer de sources d\u2019inspiration. De ces fa\u00e7ons non interactives de lire des livres et des blogs, d\u2019\u00e9couter des podcasts et de visionner des webinaires int\u00e9ressants, \u00e0 des options o\u00f9 vous avez le choix d&rsquo;interagir, tel que dans des groupes Facebook, sur Twitter, ou dans les sections de commentaires des blogs et dans des cours en ligne.&nbsp;<\/p>\n\n\n\n<p>Il n\u2019est pas n\u00e9cessaire d\u2019apporter d\u2019\u00e9norme changements pour continuer \u00e0 s\u2019entourer de sources d\u2019inspiration. Choisir de sauter le <em>small-talk<\/em> avec la famille et vos amis puis vous concentrer sur des sujets qui vous passionnent v\u00e9ritablement puis sur vos vraies valeurs peut vous permettre de rester inspir\u00e9. Vous d\u00e9couvrirez peut-\u00eatre que d\u2019autres personnes ont des int\u00e9r\u00eats similaires \u00e0 vous et peuvent avoir des conseils et des histoires vraiment inspirantes \u00e0 partager. C\u2019est ainsi que j\u2019ai d\u00e9couvert que ma belle-soeur est vraiment dou\u00e9e \u00e0 trouver des aubaines et trucs pour d\u00e9penser moins.&nbsp;<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><strong>Finalement, vous pouvez \u00e9galement assister \u00e0 des rencontres et des \u00e9v\u00e9nements comme la rencontre virtuelle FI Qu\u00e9bec que je tiendrai le 25 ao\u00fbt \u00e0 20h.&nbsp;<\/strong><\/p>\n\n\n\n<p>Pour lancer la rencontre, un panel de blogueurs r\u00e9pondra \u00e0 une s\u00e9rie de questions sur leurs propres trajectoires financi\u00e8res avant d\u2019ouvrir la parole \u00e0 tous pour des commentaires et des questions.<\/p>\n\n\n\n<p>Le panel de blogueurs sera compos\u00e9 des personnes tr\u00e8s inspirantes telles que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/lesingenieux.com\/\">Les Ing\u00e9nieux<\/a><\/li>\n\n\n\n<li>Le <a href=\"http:\/\/www.jeuneretraite.ca\/\">Jeune Retrait\u00e9<\/a><\/li>\n\n\n\n<li>Le <a href=\"https:\/\/lemillionnaireinvi.wixsite.com\/invisible\">Millionnaire Invisible<\/a><\/li>\n\n\n\n<li>Julie de <a href=\"https:\/\/planifretraite.ca\/a-propos\/\">PlanifRetraite<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/sorcierefrugale.com\/\">Sorci\u00e8re Frugale<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"has-very-dark-gray-color has-pale-cyan-blue-background-color has-text-color has-background\"><strong><em>Mise \u00e0 jour<\/em>: La rencontre a eu lieu le 25 ao\u00fbt et fut tout un succ\u00e8s! Pour \u00eatre inform\u00e9s concernant de futures rencontres, inscrivez vous ici-bas:<\/strong><\/p>\n\n\n<div class=\"\"><div class='_form_2'><\/div><script type='text\/javascript' src='https:\/\/mdorionservices.activehosted.com\/f\/embed.php?static=0&id=2&6A04B7BA75A03&nostyles=0&preview=0'><\/script><\/div>\n\n\n<p><strong><em>Comment parvenez-vous \u00e0 vous entourer de sources d\u2019inspiration? Avez-vous de bonnes histoires d\u00e9montrant comment une source d\u2019inspiration vous a conduit vers un meilleur chemin vers l\u2019un de vos objectifs?<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus vous vous entourez de sources d\u2019inspiration, plus vous avez l\u2019occasion de progresser vers vos objectifs avec assiduit\u00e9. L\u2019inspiration peut prendre plusieurs formes. Il s\u2019agit essentiellement d\u2019exemples illustrant l&rsquo;accomplissement d\u2019objectifs que vous d\u00e9sirez r\u00e9aliser ou encore de personnes qui, pour vous, ont des comportements mod\u00e8les.&nbsp; Les sources d\u2019inspiration peuvent \u00eatre non-interactives, tels que lire des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[193],"tags":[],"class_list":["post-2134","post","type-post","status-publish","format-standard","hentry","category-style-de-vie-valeurs"],"acf":[],"_links":{"self":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts\/2134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/comments?post=2134"}],"version-history":[{"count":1,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts\/2134\/revisions"}],"predecessor-version":[{"id":6046,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/posts\/2134\/revisions\/6046"}],"wp:attachment":[{"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/media?parent=2134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/categories?post=2134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/modestmillionaires.com\/fr\/wp-json\/wp\/v2\/tags?post=2134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}